{"id":9361,"date":"2021-06-24T08:10:21","date_gmt":"2021-06-24T06:10:21","guid":{"rendered":"https:\/\/wat-media.nl\/portfolio-items\/vervoerscollege-venlo\/"},"modified":"2021-06-24T08:10:21","modified_gmt":"2021-06-24T06:10:21","slug":"vervoerscollege-venlo","status":"publish","type":"avada_portfolio","link":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/","title":{"rendered":"Vervoerscollege Venlo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5643,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"portfolio_category":[58],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-9361","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-videografie-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vervoerscollege Venlo - ?!WAT Media<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vervoerscollege Venlo - ?!WAT Media\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/\" \/>\n<meta property=\"og:site_name\" content=\"?!WAT Media\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WATMedia.nl\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/\",\"name\":\"Vervoerscollege Venlo - ?!WAT Media\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Vervoerscollege-Venlo-00.jpg\",\"datePublished\":\"2021-06-24T06:10:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Vervoerscollege-Venlo-00.jpg\",\"contentUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Vervoerscollege-Venlo-00.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/vervoerscollege-venlo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/portfolio-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vervoerscollege Venlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/\",\"name\":\"?!WAT Media\",\"description\":\"Voor al uw media oplossingen\",\"publisher\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#organization\",\"name\":\"?!WAT Media\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-media-op-Wit.png\",\"contentUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-media-op-Wit.png\",\"width\":429,\"height\":155,\"caption\":\"?!WAT Media\"},\"image\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WATMedia.nl\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wat_media\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wat-media\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7PzeXY4ctU7UgGhj-hfZ6w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vervoerscollege Venlo - ?!WAT Media","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Vervoerscollege Venlo - ?!WAT Media","og_url":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/","og_site_name":"?!WAT Media","article_publisher":"https:\/\/www.facebook.com\/WATMedia.nl\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/","url":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/","name":"Vervoerscollege Venlo - ?!WAT Media","isPartOf":{"@id":"https:\/\/wat-media.nl\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/#primaryimage"},"image":{"@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/#primaryimage"},"thumbnailUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Vervoerscollege-Venlo-00.jpg","datePublished":"2021-06-24T06:10:21+00:00","breadcrumb":{"@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/#primaryimage","url":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Vervoerscollege-Venlo-00.jpg","contentUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Vervoerscollege-Venlo-00.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/wat-media.nl\/es\/portfolio-items\/vervoerscollege-venlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wat-media.nl\/es\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/wat-media.nl\/es\/portfolio-items\/"},{"@type":"ListItem","position":3,"name":"Vervoerscollege Venlo"}]},{"@type":"WebSite","@id":"https:\/\/wat-media.nl\/es\/#website","url":"https:\/\/wat-media.nl\/es\/","name":"?!WAT Media","description":"Voor al uw media oplossingen","publisher":{"@id":"https:\/\/wat-media.nl\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wat-media.nl\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wat-media.nl\/es\/#organization","name":"?!WAT Media","url":"https:\/\/wat-media.nl\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wat-media.nl\/es\/#\/schema\/logo\/image\/","url":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-media-op-Wit.png","contentUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-media-op-Wit.png","width":429,"height":155,"caption":"?!WAT Media"},"image":{"@id":"https:\/\/wat-media.nl\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WATMedia.nl\/","https:\/\/www.instagram.com\/wat_media\/","https:\/\/www.linkedin.com\/company\/wat-media\/","https:\/\/www.youtube.com\/channel\/UC7PzeXY4ctU7UgGhj-hfZ6w"]}]}},"_links":{"self":[{"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/avada_portfolio\/9361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/comments?post=9361"}],"version-history":[{"count":0,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/avada_portfolio\/9361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/media\/5643"}],"wp:attachment":[{"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/media?parent=9361"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/portfolio_category?post=9361"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/portfolio_skills?post=9361"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/wat-media.nl\/es\/wp-json\/wp\/v2\/portfolio_tags?post=9361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}