{"id":9456,"date":"2021-05-07T08:22:13","date_gmt":"2021-05-07T06:22:13","guid":{"rendered":"https:\/\/wat-media.nl\/portfolio-items\/aartman-motorservice\/"},"modified":"2021-05-07T08:22:13","modified_gmt":"2021-05-07T06:22:13","slug":"aartman-motorservice","status":"publish","type":"avada_portfolio","link":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/","title":{"rendered":"Aartman Motorservice"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4034,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"portfolio_category":[49,77],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-9456","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-fotografie-de","portfolio_category-vastgoed-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aartman Motorservice - ?!WAT Media<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aartman Motorservice - ?!WAT Media\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/\" \/>\n<meta property=\"og:site_name\" content=\"?!WAT Media\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WATMedia.nl\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/\",\"name\":\"Aartman Motorservice - ?!WAT Media\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Aartman-Motorservice-00.jpg\",\"datePublished\":\"2021-05-07T06:22:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Aartman-Motorservice-00.jpg\",\"contentUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-Media-Aartman-Motorservice-00.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/aartman-motorservice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/portfolio-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aartman Motorservice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/\",\"name\":\"?!WAT Media\",\"description\":\"Voor al uw media oplossingen\",\"publisher\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#organization\",\"name\":\"?!WAT Media\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-media-op-Wit.png\",\"contentUrl\":\"https:\\\/\\\/wat-media.nl\\\/wp-content\\\/uploads\\\/WAT-media-op-Wit.png\",\"width\":429,\"height\":155,\"caption\":\"?!WAT Media\"},\"image\":{\"@id\":\"https:\\\/\\\/wat-media.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WATMedia.nl\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wat_media\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wat-media\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7PzeXY4ctU7UgGhj-hfZ6w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aartman Motorservice - ?!WAT Media","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Aartman Motorservice - ?!WAT Media","og_url":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/","og_site_name":"?!WAT Media","article_publisher":"https:\/\/www.facebook.com\/WATMedia.nl\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/","url":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/","name":"Aartman Motorservice - ?!WAT Media","isPartOf":{"@id":"https:\/\/wat-media.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/#primaryimage"},"image":{"@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/#primaryimage"},"thumbnailUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Aartman-Motorservice-00.jpg","datePublished":"2021-05-07T06:22:13+00:00","breadcrumb":{"@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/#primaryimage","url":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Aartman-Motorservice-00.jpg","contentUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-Media-Aartman-Motorservice-00.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/wat-media.nl\/de\/portfolio-items\/aartman-motorservice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wat-media.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/wat-media.nl\/de\/portfolio-items\/"},{"@type":"ListItem","position":3,"name":"Aartman Motorservice"}]},{"@type":"WebSite","@id":"https:\/\/wat-media.nl\/de\/#website","url":"https:\/\/wat-media.nl\/de\/","name":"?!WAT Media","description":"Voor al uw media oplossingen","publisher":{"@id":"https:\/\/wat-media.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wat-media.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wat-media.nl\/de\/#organization","name":"?!WAT Media","url":"https:\/\/wat-media.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wat-media.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-media-op-Wit.png","contentUrl":"https:\/\/wat-media.nl\/wp-content\/uploads\/WAT-media-op-Wit.png","width":429,"height":155,"caption":"?!WAT Media"},"image":{"@id":"https:\/\/wat-media.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WATMedia.nl\/","https:\/\/www.instagram.com\/wat_media\/","https:\/\/www.linkedin.com\/company\/wat-media\/","https:\/\/www.youtube.com\/channel\/UC7PzeXY4ctU7UgGhj-hfZ6w"]}]}},"_links":{"self":[{"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/avada_portfolio\/9456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/comments?post=9456"}],"version-history":[{"count":0,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/avada_portfolio\/9456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/media\/4034"}],"wp:attachment":[{"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/media?parent=9456"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/portfolio_category?post=9456"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/portfolio_skills?post=9456"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/wat-media.nl\/de\/wp-json\/wp\/v2\/portfolio_tags?post=9456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}